{"id":11420,"date":"2021-05-11T14:16:33","date_gmt":"2021-05-11T12:16:33","guid":{"rendered":"https:\/\/www.mafuturemaison.fr\/dossier\/?p=11420"},"modified":"2022-03-04T09:53:54","modified_gmt":"2022-03-04T08:53:54","slug":"le-garage-une-piece-multifonction","status":"publish","type":"post","link":"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/","title":{"rendered":"Le garage, une pi\u00e8ce multifonction"},"content":{"rendered":"<p class=\"Standard\" style=\"text-align: left;\" align=\"center\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft  wp-image-11421\" src=\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2021\/05\/garage-e1620732175983-300x218.jpg\" alt=\"garage\" width=\"226\" height=\"164\" srcset=\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2021\/05\/garage-e1620732175983-300x218.jpg 300w, https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2021\/05\/garage-e1620732175983.jpg 400w\" sizes=\"auto, (max-width: 226px) 100vw, 226px\" \/>Espace utile pour garer les voitures et pour les prot\u00e9ger des intemp\u00e9ries, le garage est aussi tr\u00e8s r\u00e9guli\u00e8rement utilis\u00e9 comme pi\u00e8ce de stockage. Il existe plusieurs fa\u00e7ons de construire un garage, en fonction de vos envies, de vos besoins et de vos moyens. Mais avant de valider votre projet de garage avec le constructeur de votre future maison, il est n\u00e9cessaire de se poser quelques questions. Voici un petit r\u00e9sum\u00e9\u00a0des points \u00e0 \u00e9tudier pour\u00a0vous aider dans votre choix.<\/strong><\/p>\n<h2 class=\"Standard\">Un garage attenant \u00e0 la maison ou ind\u00e9pendant ?<\/h2>\n<p class=\"Standard\"><strong>La premi\u00e8re question \u00e0 se poser lorsque l&rsquo;on choisit de faire construire un garage est de savoir s&rsquo;il sera attenant \u00e0 la maison ou s&rsquo;il sera ind\u00e9pendant.<\/strong><\/p>\n<h3 class=\"Standard\">Exemple de maison avec garage ind\u00e9pendant construite par Maisons Barbey Maillard<\/h3>\n<p><a href=\"https:\/\/www.lesmaisonsbm.com\/plans-maison\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12105 size-full\" src=\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/garage-independant.jpg\" alt=\"garage-ind\u00e9pendant\" width=\"750\" height=\"392\" srcset=\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/garage-independant.jpg 750w, https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/garage-independant-300x157.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p>Ici, la taille et la configuration du terrain permettent de construire un garage isol\u00e9 de la maison et spacieux. Son acc\u00e8s est \u00e9galement ind\u00e9pendant, et une all\u00e9e am\u00e9nag\u00e9e pour rejoindre la maison.<\/p>\n<h3 class=\"Standard\"><strong>Exemple d&rsquo;une maison avec garage accol\u00e9 construite par Maisons Barbey Maillard<\/strong><\/h3>\n<p class=\"Standard\"><strong>Lorsque le garage est attenant<\/strong>, il existe un <strong>acc\u00e8s direct entre la maison et le garage, sans\u00a0\u00eatre oblig\u00e9 de sortir pour y acc\u00e9der.<\/strong>\u00a0Dans ce cas, il peut \u00eatre <strong>int\u00e9gr\u00e9 ou accol\u00e9<\/strong>.<\/p>\n<p class=\"Standard\"><a href=\"https:\/\/www.lesmaisonsbm.com\/nos-realisations\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12107 size-full\" src=\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/MBvincennes-garage.jpg\" alt=\"garage accol\u00e9\" width=\"750\" height=\"458\" srcset=\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/MBvincennes-garage.jpg 750w, https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/MBvincennes-garage-300x183.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<p class=\"Standard\">L&rsquo;avantage est surtout lorsque le temps n&rsquo;est pas au rendez-vous, la voiture est gar\u00e9e et vous n&rsquo;\u00eates pas mouill\u00e9 pour rentrer chez vous.<\/p>\n<p class=\"Standard\">Dans la maison pr\u00e9sent\u00e9e ici, <strong>le garage est construit \u00e0 c\u00f4t\u00e9 du b\u00e2ti principal<\/strong> et reprend les formes et l&rsquo;esth\u00e9tique de la maison, sans pour autant nuire \u00e0 son \u00e9quilibre et son harmonie. Il est accessible depuis l&rsquo;int\u00e9rieur de la maison, via la cuisine et\/ou le cellier.<\/p>\n<h3 class=\"Standard\"><strong>Exemple d&rsquo;une maison avec garage int\u00e9gr\u00e9\u00a0construite par Maisons Barbey Maillard<\/strong><\/h3>\n<p>Ici, <strong>le garage est int\u00e9gr\u00e9 \u00e0 la maison<\/strong>, dont le plan\u00a0comprend\u00a0d\u00e8s le d\u00e9part un espace pens\u00e9 pour l&rsquo;accueillir. L&rsquo;avanc\u00e9e de la fa\u00e7ade avant abrite le garage, tout en structurant l&rsquo;architecture et permettant un habillage graphique, qui donne \u00e0 sa maison sa personnalit\u00e9.<\/p>\n<p><a href=\"https:\/\/www.lesmaisonsbm.com\/creations-maison\/\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12108 size-full\" src=\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2021\/05\/garage-integre.jpg\" alt=\"garage int\u00e9gr\u00e9\" width=\"750\" height=\"390\" srcset=\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2021\/05\/garage-integre.jpg 750w, https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2021\/05\/garage-integre-300x156.jpg 300w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/a><\/p>\n<h3 class=\"Standard\">Exemple\u00a0d&rsquo;une maison de ville avec garage semi-enterr\u00e9 construite par Maisons Barbey Maillard<\/h3>\n<p class=\"Standard\"><strong>Si le terrain est en pente<\/strong>, il ne faut pas h\u00e9siter \u00e0 faire construire <strong>un garage enterr\u00e9 ou semi-enterr\u00e9<\/strong>, ce qui permet de ne pas empi\u00e9ter sur le terrain.<\/p>\n<p class=\"Standard\"><a href=\"https:\/\/www.mafuturemaison.fr\/annonce\/modele-maison?brand=3\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-12102 size-full\" src=\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/151m-garage.jpg\" alt=\"garage semi enterr\u00e9\" width=\"728\" height=\"503\" srcset=\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/151m-garage.jpg 728w, https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/151m-garage-300x207.jpg 300w\" sizes=\"auto, (max-width: 728px) 100vw, 728px\" \/><\/a><\/p>\n<p class=\"Standard\"><strong>Dans cet exemple, <\/strong>le garage est situ\u00e9 en contrebas, ce qui permet de gagner de l&rsquo;espace dans le jardin, et de conserver\u00a0les proportions et les volumes de l&rsquo;architecture.<\/p>\n<p class=\"Standard\">Il est aussi possible de construire <strong>un garage plus loin sur le terrain comme une pi\u00e8ce ind\u00e9pendante<\/strong>. Il est donc totalement s\u00e9par\u00e9 de la maison.<\/p>\n<p class=\"Standard\"><strong><span style=\"text-decoration: underline; color: #3366ff;\">Bon \u00e0 savoir :<\/span> Un garage attenant est la solution la moins on\u00e9reuse par rapport \u00e0 un garage ind\u00e9pendant puisque les fondations et la construction sont faites dans la continuit\u00e9 de la maison. Il s&rsquo;agit simplement d&rsquo;une pi\u00e8ce suppl\u00e9mentaire dans le prolongement tout comme une chambre.<\/strong><\/p>\n<h2 class=\"Standard\">Quelle superficie\u00a0pour un garage ?<\/h2>\n<p><strong>La superficie de votre garage d\u00e9pend de plusieurs param\u00e8tres<\/strong>, et l\u00e0 encore il faudra vous poser quelques questions.<\/p>\n<p class=\"Standard\"><strong>Si le garage servira \u00e0 garer seulement une voiture<\/strong>, un garage de <strong>10\u00a0\u00e0 15m\u00b2<\/strong> peut suffire.<\/p>\n<p class=\"Standard\">En revanche, <strong>dans l&rsquo;optique de l&rsquo;utiliser aussi comme espace de stockage ou de bricolage<\/strong>, optez plut\u00f4t pour un garage de <strong>20 m<\/strong>\u00b2.<\/p>\n<p>De m\u00eame, pour y <strong>garer deux voitures<\/strong>, il faudra choisir si elle seront gar\u00e9es c\u00f4te \u00e0 c\u00f4te ou l&rsquo;une derri\u00e8re l&rsquo;autre. <strong>Pour les garer c\u00f4te \u00e0 c\u00f4te, il faut songer \u00e0 une largeur assez importante et donc \u00e0 une porte avec 2 entr\u00e9es<\/strong>. Cela peut faire grimper le prix de votre garage, surtout si les portes sont motoris\u00e9es.<\/p>\n<p class=\"Standard\"><span style=\"color: #3366ff;\">Attention<\/span> tout de m\u00eame, <strong>la superficie du garage est comptabilis\u00e9e pour le calcul de la <a title=\"Bien calculer le prix de votre maison\" href=\"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/bien-calculer-le-prix-de-votre-maison\/\" target=\"_blank\">taxe fonci\u00e8re et de la taxe d&rsquo;habitation<\/a><\/strong>. N&rsquo;h\u00e9sitez pas \u00e0 <a title=\"garage\" href=\"https:\/\/www.ecologie.gouv.fr\/fiscalite-sur-location-garages-et-places-stationnement\" target=\"_blank\">vous renseigner<\/a> aupr\u00e8s de la mairie de votre commune avant de choisir la taille du garage afin d&rsquo;\u00e9viter les mauvaises surprises.<\/p>\n<h2>Une plus-value \u00e0 votre maison<\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-12109\" src=\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2021\/05\/plus-value-300x173.jpg\" alt=\"plus-value\" width=\"300\" height=\"173\" srcset=\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2021\/05\/plus-value-300x173.jpg 300w, https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2021\/05\/plus-value.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/>Le garage peut \u00eatre construit\u00a0<strong>en parpaings<\/strong>, mais il peut aussi \u00eatre <strong>en bois pr\u00e9fabriqu\u00e9,<\/strong> ce qui ajoute du cachet \u00e0 votre maison.<\/p>\n<p class=\"Standard\">Comme vu plus haut, <strong>la surface du garage est consid\u00e9r\u00e9e comme une surface suppl\u00e9mentaire qui apporte une plus-value \u00e0 votre maison dans le cas d&rsquo;une revente<\/strong>.<\/p>\n<p class=\"Standard\"><strong>Un garage attenant peut tr\u00e8s bien \u00eatre transform\u00e9 en chambre pour augmenter la surface habitable de la maison, tout comme un garage ind\u00e9pendant peut \u00eatre transform\u00e9 en chambre d&rsquo;invit\u00e9s.<\/strong><\/p>\n<h4 class=\"Standard\" style=\"text-align: center;\"><a title=\"Barbey Maillard\" href=\"https:\/\/www.lesmaisonsbm.com\/plans-maison\/\" target=\"_blank\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-4892\" src=\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2012\/01\/logo-barbey.jpg\" alt=\"Barbey Maillard\" width=\"200\" height=\"100\" \/>D\u00e9couvrez\u00a0plus de mod\u00e8les\u00a0et d&rsquo;informations sur le constructeur de Maisons Barbey Maillard<\/strong><\/a><\/h4>\n","protected":false},"excerpt":{"rendered":"<p>Espace utile pour garer les voitures et pour les prot\u00e9ger des intemp\u00e9ries, le garage est aussi tr\u00e8s r\u00e9guli\u00e8rement utilis\u00e9 comme pi\u00e8ce de stockage. Il existe plusieurs fa\u00e7ons de construire un garage, en fonction de vos envies, de vos besoins et de vos moyens. Mais avant de valider votre projet de garage avec le constructeur de &hellip;<\/p>\n","protected":false},"author":1,"featured_media":12106,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,7,2,8],"tags":[844,845,846,655],"class_list":["post-11420","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites","category-conseils-pour-faire-construire","category-construire","category-styles-et-architectures","tag-garage-accole","tag-garage-independant","tag-garage-pour-deux-voitures","tag-maison-avec-garage"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Le garage, une pi\u00e8ce multifonction - Ma Future Maison<\/title>\n<meta name=\"description\" content=\"Utile pour garer et prot\u00e9ger sa voiture des intemp\u00e9ries, le garage est aussi utilis\u00e9 comme pi\u00e8ce de stockage. Nos conseils pour faire construire son garage.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le garage, une pi\u00e8ce multifonction - Ma Future Maison\" \/>\n<meta property=\"og:description\" content=\"Utile pour garer et prot\u00e9ger sa voiture des intemp\u00e9ries, le garage est aussi utilis\u00e9 comme pi\u00e8ce de stockage. Nos conseils pour faire construire son garage.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma Future Maison\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/MaFutureMaison\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-11T12:16:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-04T08:53:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/MADISON-garage.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"472\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cl\u00e9ment\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cl\u00e9ment\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/\",\"url\":\"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/\",\"name\":\"Le garage, une pi\u00e8ce multifonction - Ma Future Maison\",\"isPartOf\":{\"@id\":\"https:\/\/www.mafuturemaison.fr\/dossier\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/MADISON-garage.jpg\",\"datePublished\":\"2021-05-11T12:16:33+00:00\",\"dateModified\":\"2022-03-04T08:53:54+00:00\",\"author\":{\"@id\":\"https:\/\/www.mafuturemaison.fr\/dossier\/#\/schema\/person\/f994f1f3783d6073b7eb98c4ff13e131\"},\"description\":\"Utile pour garer et prot\u00e9ger sa voiture des intemp\u00e9ries, le garage est aussi utilis\u00e9 comme pi\u00e8ce de stockage. Nos conseils pour faire construire son garage.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/#primaryimage\",\"url\":\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/MADISON-garage.jpg\",\"contentUrl\":\"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/MADISON-garage.jpg\",\"width\":750,\"height\":472,\"caption\":\"Madison-garage\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.mafuturemaison.fr\/dossier\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le garage, une pi\u00e8ce multifonction\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mafuturemaison.fr\/dossier\/#website\",\"url\":\"https:\/\/www.mafuturemaison.fr\/dossier\/\",\"name\":\"Ma Future Maison\",\"description\":\"Conseils et annonces pour faire construire sa maison\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mafuturemaison.fr\/dossier\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mafuturemaison.fr\/dossier\/#\/schema\/person\/f994f1f3783d6073b7eb98c4ff13e131\",\"name\":\"Cl\u00e9ment\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.mafuturemaison.fr\/dossier\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ec243a4040373b27c6399de0bb4b792b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ec243a4040373b27c6399de0bb4b792b?s=96&d=mm&r=g\",\"caption\":\"Cl\u00e9ment\"},\"url\":\"https:\/\/www.mafuturemaison.fr\/dossier\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le garage, une pi\u00e8ce multifonction - Ma Future Maison","description":"Utile pour garer et prot\u00e9ger sa voiture des intemp\u00e9ries, le garage est aussi utilis\u00e9 comme pi\u00e8ce de stockage. Nos conseils pour faire construire son garage.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/","og_locale":"fr_FR","og_type":"article","og_title":"Le garage, une pi\u00e8ce multifonction - Ma Future Maison","og_description":"Utile pour garer et prot\u00e9ger sa voiture des intemp\u00e9ries, le garage est aussi utilis\u00e9 comme pi\u00e8ce de stockage. Nos conseils pour faire construire son garage.","og_url":"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/","og_site_name":"Ma Future Maison","article_publisher":"https:\/\/www.facebook.com\/MaFutureMaison\/","article_published_time":"2021-05-11T12:16:33+00:00","article_modified_time":"2022-03-04T08:53:54+00:00","og_image":[{"width":750,"height":472,"url":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/MADISON-garage.jpg","type":"image\/jpeg"}],"author":"Cl\u00e9ment","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Cl\u00e9ment","Dur\u00e9e de lecture estim\u00e9e":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/","url":"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/","name":"Le garage, une pi\u00e8ce multifonction - Ma Future Maison","isPartOf":{"@id":"https:\/\/www.mafuturemaison.fr\/dossier\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/#primaryimage"},"image":{"@id":"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/MADISON-garage.jpg","datePublished":"2021-05-11T12:16:33+00:00","dateModified":"2022-03-04T08:53:54+00:00","author":{"@id":"https:\/\/www.mafuturemaison.fr\/dossier\/#\/schema\/person\/f994f1f3783d6073b7eb98c4ff13e131"},"description":"Utile pour garer et prot\u00e9ger sa voiture des intemp\u00e9ries, le garage est aussi utilis\u00e9 comme pi\u00e8ce de stockage. Nos conseils pour faire construire son garage.","breadcrumb":{"@id":"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/#primaryimage","url":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/MADISON-garage.jpg","contentUrl":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-content\/uploads\/2022\/03\/MADISON-garage.jpg","width":750,"height":472,"caption":"Madison-garage"},{"@type":"BreadcrumbList","@id":"https:\/\/www.mafuturemaison.fr\/dossier\/construire\/le-garage-une-piece-multifonction\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.mafuturemaison.fr\/dossier\/"},{"@type":"ListItem","position":2,"name":"Le garage, une pi\u00e8ce multifonction"}]},{"@type":"WebSite","@id":"https:\/\/www.mafuturemaison.fr\/dossier\/#website","url":"https:\/\/www.mafuturemaison.fr\/dossier\/","name":"Ma Future Maison","description":"Conseils et annonces pour faire construire sa maison","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mafuturemaison.fr\/dossier\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.mafuturemaison.fr\/dossier\/#\/schema\/person\/f994f1f3783d6073b7eb98c4ff13e131","name":"Cl\u00e9ment","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.mafuturemaison.fr\/dossier\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/ec243a4040373b27c6399de0bb4b792b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ec243a4040373b27c6399de0bb4b792b?s=96&d=mm&r=g","caption":"Cl\u00e9ment"},"url":"https:\/\/www.mafuturemaison.fr\/dossier\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-json\/wp\/v2\/posts\/11420","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-json\/wp\/v2\/comments?post=11420"}],"version-history":[{"count":12,"href":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-json\/wp\/v2\/posts\/11420\/revisions"}],"predecessor-version":[{"id":12110,"href":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-json\/wp\/v2\/posts\/11420\/revisions\/12110"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-json\/wp\/v2\/media\/12106"}],"wp:attachment":[{"href":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-json\/wp\/v2\/media?parent=11420"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-json\/wp\/v2\/categories?post=11420"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mafuturemaison.fr\/dossier\/wp-json\/wp\/v2\/tags?post=11420"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}